{"id":1070,"date":"2024-03-01T12:51:52","date_gmt":"2024-03-01T12:51:52","guid":{"rendered":"https:\/\/dummy.xtemos.com\/woodmart2\/vegetables-elementor\/?page_id=13"},"modified":"2025-05-15T15:02:03","modified_gmt":"2025-05-15T15:02:03","slug":"home","status":"publish","type":"page","link":"https:\/\/dr-glo.store\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1070\" class=\"elementor elementor-1070\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-4d60520 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"4d60520\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e6a83e elementor--h-position-center elementor--v-position-middle elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"6e6a83e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay_speed&quot;:10000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-5aa372a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"WhatsApp Image 2025-02-16 at 8.19.35 PM\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-317d6a2 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"WhatsApp Image 2025-02-04 at 6.17.45 PM (1)\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-0f4484c e-flex e-con-boxed e-con e-parent\" data-id=\"0f4484c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8838dfb wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8838dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Shop By Brand<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8984a wd-width-100 elementor-widget elementor-widget-wd_banner_carousel\" data-id=\"cc8984a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_banner_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-container banners-carousel-wrapper\">\n\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t<div class=\"wd-carousel wd-grid banners-carousel\" data-speed=\"4000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5;--wd-col-md:4;--wd-col-sm:3;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-dcef9e0\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164809.639.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164809.639.png 400w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164809.639-150x75.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164809.639-300x150.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=149\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-c1d814c\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/bonacure1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/bonacure1.png 500w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/bonacure1-150x60.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/bonacure1-300x120.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=147\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-d12896b\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"628\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem.webp 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem-150x79.webp 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem-300x157.webp 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem-1024x536.webp 1024w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/logo-topicrem-768x402.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=146\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-8216049\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165430.886.png\" class=\"attachment-full size-full\" alt=\"Heliabrine\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165430.886.png 400w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165430.886-150x75.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165430.886-300x150.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=155\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-e76347e\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1415\" height=\"547\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie.jpg 1415w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie-150x58.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie-1200x464.jpg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie-300x116.jpg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie-1024x396.jpg 1024w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Logo_noreva_Neu_Kopie-768x297.jpg 768w\" sizes=\"(max-width: 1415px) 100vw, 1415px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=142\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-eb1c17e\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165000.169.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165000.169.png 400w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165000.169-150x75.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T165000.169-300x150.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=151\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-9e52ff8\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164909.622.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164909.622.png 400w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164909.622-150x75.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164909.622-300x150.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=150\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper wd-carousel-item elementor-repeater-item-552584c\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-none color-scheme- banner-btn-size-default banner-btn-style-default wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-without-height\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164639.680.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164639.680.png 400w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164639.680-150x75.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-13T164639.680-300x150.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dr-glo.store\/shop\/?filtering=1&#038;filter_product_brand=148\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Banner link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-cb2551c e-flex e-con-boxed e-con e-parent\" data-id=\"cb2551c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-6bac38d e-flex e-con-boxed e-con e-child\" data-id=\"6bac38d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a32019 elementor-widget elementor-widget-wd_infobox\" data-id=\"5a32019\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-middle\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tWeekly Offers\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02037c3 elementor-widget elementor-widget-wd_button\" data-id=\"02037c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-large btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/dr-glo.store\/en\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVisit Shop\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da6f555 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"da6f555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element\">\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products pagination-arrows grid-columns-4 elements-grid products-bordered-grid-ins title-line-one wd-grid-g wd-stretch-cont-lg wd-stretch-cont-sm wd-products-with-bg wd-products-with-shadow\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;slides_per_view_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;3.5&quot;,&quot;sizes&quot;:[]},&quot;slides_per_view_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.5&quot;,&quot;sizes&quot;:[]},&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;hide_scrollbar_tablet&quot;:&quot;&quot;,&quot;hide_scrollbar_mobile&quot;:&quot;&quot;,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination&quot;:&quot;arrows&quot;,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;quick&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:&quot;1&quot;,&quot;stretch_product_mobile&quot;:&quot;1&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;1&quot;,&quot;products_bordered_grid_style&quot;:&quot;inside&quot;,&quot;products_with_background&quot;:&quot;1&quot;,&quot;products_shadow&quot;:&quot;1&quot;,&quot;img_size&quot;:&quot;medium_large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-1897 status-publish instock product_cat-skin-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1897\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\" class=\"product-image-link\" aria-label=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png\" class=\"attachment-medium_large size-medium_large\" alt=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"1897\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"1897\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=1897\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1897\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"1897\" data-product_sku=\"3700111428478\" aria-label=\"Add to cart: &ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1897\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\">-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>109,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick wd-col product-grid-item product type-product post-4244 status-publish outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"4244\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" class=\"product-image-link\" aria-label=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png\" class=\"attachment-medium_large size-medium_large\" alt=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4244\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4244\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4244\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4244\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4244\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\">% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>235,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product wcpa_has_options type-product post-2868 status-publish last instock product_cat-medicine-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"2868\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"AV AVOHEX M W 300 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png\" class=\"attachment-medium_large size-medium_large\" alt=\"AV AVOHEX M W 300 \u0645\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"2868\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"2868\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2868\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button wcpa_add_to_cart_button add-to-cart-loop\" data-product_id=\"2868\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo; has been added to your cart\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2868\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\">AV AVOHEX M W 300 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/medicine-2\/\" rel=\"tag\">\u0627\u0644\u0627\u062f\u0648\u064a\u0629 \u0627\u0644\u0648\u0635\u0641\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>37,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-4840 status-publish first instock product_cat-hair-2 product_cat-scalp-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"4840\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4840\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4840\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4840\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4840\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4840\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4840\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/hair-2\/\" rel=\"tag\">\u0627\u0644\u0634\u0639\u0631<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/scalp-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0641\u0631\u0648\u0629 \u0627\u0644\u0631\u0623\u0633<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>132,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-4867 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-serums-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"4867\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4867\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4867\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4867\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4867\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4867\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4867\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>350,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-4876 status-publish instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4876\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1502x1536.jpeg 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1200x1227.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01.jpeg 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4876\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4876\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4876\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4876\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4876\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4876\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>310,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-3028 status-publish last instock product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"3028\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-293x300.jpg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1001x1024.jpg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1200x1228.jpg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-150x153.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f.jpg 1251w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3028\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3028\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3028\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3028\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3028\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3028\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>115,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-4845 status-publish first instock product_cat-skin-care-2 product_cat-serums-2 product_cat-body-lotions-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"4845\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-293x300.png 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1001x1024.png 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1502x1536.png 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1200x1227.png 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-150x153.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d.png 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4845\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4845\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4845\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4845\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4845\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4845\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-ajax-arrows wd-hover-1 wd-pos-sep wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-3980729 e-flex e-con-boxed e-con e-parent\" data-id=\"3980729\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-2ab2875 e-flex e-con-boxed e-con e-child\" data-id=\"2ab2875\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69436f0 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"69436f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Offers<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403dee1 elementor-widget elementor-widget-wd_button\" data-id=\"403dee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-large btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/dr-glo.store\/en\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVisit Shop\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de0eca wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"1de0eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-550\" class=\"wd-carousel-container  wd-products-element wd-products products wd-products-with-bg wd-products-with-shadow wd-stretch-cont-lg wd-stretch-cont-sm products-bordered-grid-ins title-line-one\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid wd-stretch-cont-lg wd-stretch-cont-sm\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5.5;--wd-col-md:3.5;--wd-col-sm:1.5;--wd-gap:20px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-1897 status-publish instock product_cat-skin-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1897\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\" class=\"product-image-link\" aria-label=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png\" class=\"attachment-medium_large size-medium_large\" alt=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"1897\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"1897\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=1897\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1897\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"1897\" data-product_sku=\"3700111428478\" aria-label=\"Add to cart: &ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1897\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\">-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>109,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-4244 status-publish outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"4244\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" class=\"product-image-link\" aria-label=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png\" class=\"attachment-medium_large size-medium_large\" alt=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4244\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4244\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4244\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4244\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4244\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\">% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>235,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product wcpa_has_options type-product post-2868 status-publish last instock product_cat-medicine-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"2868\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"AV AVOHEX M W 300 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png\" class=\"attachment-medium_large size-medium_large\" alt=\"AV AVOHEX M W 300 \u0645\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"2868\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"2868\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2868\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button wcpa_add_to_cart_button add-to-cart-loop\" data-product_id=\"2868\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo; has been added to your cart\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2868\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\">AV AVOHEX M W 300 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/medicine-2\/\" rel=\"tag\">\u0627\u0644\u0627\u062f\u0648\u064a\u0629 \u0627\u0644\u0648\u0635\u0641\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>37,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4840 status-publish first instock product_cat-hair-2 product_cat-scalp-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"4840\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4840\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4840\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4840\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4840\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4840\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4840\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/hair-2\/\" rel=\"tag\">\u0627\u0644\u0634\u0639\u0631<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/scalp-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0641\u0631\u0648\u0629 \u0627\u0644\u0631\u0623\u0633<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>132,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4867 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-serums-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"4867\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4867\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4867\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4867\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4867\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4867\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4867\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>350,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4876 status-publish instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4876\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1502x1536.jpeg 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1200x1227.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01.jpeg 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4876\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4876\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4876\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4876\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4876\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4876\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>310,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3028 status-publish last instock product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"3028\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-293x300.jpg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1001x1024.jpg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1200x1228.jpg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-150x153.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f.jpg 1251w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3028\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3028\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3028\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3028\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3028\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3028\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>115,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4845 status-publish first instock product_cat-skin-care-2 product_cat-serums-2 product_cat-body-lotions-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"4845\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-293x300.png 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1001x1024.png 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1502x1536.png 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1200x1227.png 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-150x153.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d.png 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4845\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4845\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4845\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4845\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4845\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4845\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4871 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-cleansers-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"4871\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-768x785.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-768x785.png 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-293x300.png 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1001x1024.png 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1502x1536.png 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1200x1227.png 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-150x153.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1.png 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4871\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4871\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4871\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4871\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4871\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4871\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cleansers-2\/\" rel=\"tag\">\u063a\u0633\u0648\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>184,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3040 status-publish instock product_cat-skin-care-2 product_cat-creams-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"3040\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-768x785.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-768x785.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1502x1536.jpeg 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1200x1227.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51.jpeg 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3040\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3040\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3040\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3040\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3040\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3040\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\">Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/creams-2\/\" rel=\"tag\">\u0643\u0631\u064a\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4836 status-publish last instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"4836\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-768x768.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-300x300.jpeg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-150x150.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-600x600.jpeg 600w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233.jpeg 770w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4836\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4836\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4836\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4836\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4836\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4836\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\">Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>172,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3020 status-publish first instock product_cat-158 product_cat-conditioners-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"3020\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-768x768.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-300x300.jpeg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1024x1024.jpeg 1024w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-150x150.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1536x1536.jpeg 1536w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-600x600.jpeg 600w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1200x1200.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4.jpeg 1600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3020\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3020\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3020\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3020\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3020\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3020\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\">Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics\/skin-care\/%d8%a7%d9%84%d8%b4%d9%81%d8%a7%d9%87\/\" rel=\"tag\">\u0627\u0644\u0634\u0641\u0627\u0647<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/conditioners-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-scroll\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-bf57260 e-flex e-con-boxed e-con e-parent\" data-id=\"bf57260\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-cda72c5 e-flex e-con-boxed e-con e-child\" data-id=\"cda72c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a964bf wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8a964bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Skin Care Products<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c67a2 elementor-widget elementor-widget-wd_button\" data-id=\"50c67a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-large btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/dr-glo.store\/en\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVisit Shop\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8613c elementor-widget elementor-widget-wd_products_tabs\" data-id=\"5a8613c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs wd-products-tabs tabs-design-default\">\n\t\t\t<div class=\"wd-tabs-header text-left\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper tabs-navigation-wrapper\">\n\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs products-tabs-title wd-style-underline wd-icon-pos-top\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li data-atts=\"{&quot;layout&quot;:&quot;grid&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;spacing&quot;:&quot;20&quot;,&quot;spacing_tablet&quot;:&quot;20&quot;,&quot;spacing_mobile&quot;:&quot;20&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;inherit&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product_tablet&quot;:0,&quot;stretch_product_mobile&quot;:0,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:0,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;1&quot;,&quot;products_bordered_grid_style&quot;:&quot;inside&quot;,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;1&quot;,&quot;products_color_scheme&quot;:&quot;default&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;elementor&quot;:true,&quot;sync_parent_id&quot;:null,&quot;slides_per_view&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;wrap&quot;:null,&quot;autoheight&quot;:null,&quot;autoplay&quot;:null,&quot;speed&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_child_id&quot;:null,&quot;img_size_custom&quot;:null,&quot;stretch_product&quot;:null,&quot;grid_gallery&quot;:&quot;&quot;,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;post_type&quot;:&quot;bestselling&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;include&quot;:null,&quot;taxonomies&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;offset&quot;:&quot;&quot;,&quot;query_type&quot;:&quot;OR&quot;,&quot;order&quot;:&quot;&quot;,&quot;hide_out_of_stock&quot;:&quot;no&quot;,&quot;meta_key&quot;:null,&quot;exclude&quot;:&quot;&quot;}\" class=\" wd-active\">\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tab-label nav-link-text\">\n\t\t\t\t\t\t\t\t\t\tBestsellers\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li data-atts=\"{&quot;layout&quot;:&quot;grid&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;spacing&quot;:&quot;20&quot;,&quot;spacing_tablet&quot;:&quot;20&quot;,&quot;spacing_mobile&quot;:&quot;20&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;inherit&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product_tablet&quot;:0,&quot;stretch_product_mobile&quot;:0,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:0,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;1&quot;,&quot;products_bordered_grid_style&quot;:&quot;inside&quot;,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;1&quot;,&quot;products_color_scheme&quot;:&quot;default&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;elementor&quot;:true,&quot;sync_parent_id&quot;:null,&quot;slides_per_view&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;wrap&quot;:null,&quot;autoheight&quot;:null,&quot;autoplay&quot;:null,&quot;speed&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_child_id&quot;:null,&quot;img_size_custom&quot;:null,&quot;stretch_product&quot;:null,&quot;grid_gallery&quot;:&quot;&quot;,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;post_type&quot;:&quot;new&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;include&quot;:null,&quot;taxonomies&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;offset&quot;:&quot;&quot;,&quot;query_type&quot;:&quot;OR&quot;,&quot;order&quot;:&quot;&quot;,&quot;hide_out_of_stock&quot;:&quot;no&quot;,&quot;meta_key&quot;:null,&quot;exclude&quot;:&quot;&quot;}\" class=\"\">\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tab-label nav-link-text\">\n\t\t\t\t\t\t\t\t\t\tNew \t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-products-element wd-tab-content wd-active wd-in\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid products-bordered-grid-ins title-line-one wd-grid-g wd-stretch-cont-lg wd-stretch-cont-md wd-stretch-cont-sm wd-products-with-shadow\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;post_type&quot;:&quot;bestselling&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;1&quot;,&quot;products_bordered_grid_style&quot;:&quot;inside&quot;,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;1&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;force_not_ajax&quot;:&quot;no&quot;,&quot;wrapper_classes&quot;:&quot; wd-tab-content wd-active wd-in&quot;,&quot;elementor&quot;:true}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-1897 status-publish instock product_cat-skin-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1897\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\" class=\"product-image-link\" aria-label=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png\" class=\"attachment-large size-large\" alt=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"1897\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\">-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>109,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=1897\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1897\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"1897\" data-product_sku=\"3700111428478\" aria-label=\"Add to cart: &ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1897\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"1897\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-4964 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-cleansers-2 product_cat-creams-2 product_cat-conditioners-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"4964\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d9%86%d8%b3%d9%8a-%d9%88%d8%a7%d9%8a%d8%aa-%d8%ba%d8%b3%d9%88%d9%84-%d9%83%d8%b1%d9%8a%d9%85-%d9%84%d8%aa%d9%81%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%ac%d8%b3%d9%85-%d9%88-%d8%a7%d9%84\/\" class=\"product-image-link\" aria-label=\"\u0633\u064a\u0646\u0633\u064a \u0648\u0627\u064a\u062a &#8211;  \u063a\u0633\u0648\u0644 + \u0643\u0631\u064a\u0645 \u0644\u062a\u0641\u062a\u064a\u062d \u0627\u0644\u062c\u0633\u0645 \u0648 \u0627\u0644\u0623\u0645\u0627\u0643\u0646 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \/ SENSI WHITE KIT\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-576x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-576x1024.jpg 576w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-169x300.jpg 169w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-768x1365.jpg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-864x1536.jpg 864w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-1152x2048.jpg 1152w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-1200x2133.jpg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-150x267.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/12\/IMG_5106-1-scaled.jpg 1440w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4964\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d9%86%d8%b3%d9%8a-%d9%88%d8%a7%d9%8a%d8%aa-%d8%ba%d8%b3%d9%88%d9%84-%d9%83%d8%b1%d9%8a%d9%85-%d9%84%d8%aa%d9%81%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%ac%d8%b3%d9%85-%d9%88-%d8%a7%d9%84\/\">\u0633\u064a\u0646\u0633\u064a \u0648\u0627\u064a\u062a &#8211;  \u063a\u0633\u0648\u0644 + \u0643\u0631\u064a\u0645 \u0644\u062a\u0641\u062a\u064a\u062d \u0627\u0644\u062c\u0633\u0645 \u0648 \u0627\u0644\u0623\u0645\u0627\u0643\u0646 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \/ SENSI WHITE KIT<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cleansers-2\/\" rel=\"tag\">\u063a\u0633\u0648\u0644<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/creams-2\/\" rel=\"tag\">\u0643\u0631\u064a\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/conditioners-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>339,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4964\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4964\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4964\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;\u0633\u064a\u0646\u0633\u064a \u0648\u0627\u064a\u062a -  \u063a\u0633\u0648\u0644 + \u0643\u0631\u064a\u0645 \u0644\u062a\u0641\u062a\u064a\u062d \u0627\u0644\u062c\u0633\u0645 \u0648 \u0627\u0644\u0623\u0645\u0627\u0643\u0646 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \/ SENSI WHITE KIT&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;\u0633\u064a\u0646\u0633\u064a \u0648\u0627\u064a\u062a -  \u063a\u0633\u0648\u0644 + \u0643\u0631\u064a\u0645 \u0644\u062a\u0641\u062a\u064a\u062d \u0627\u0644\u062c\u0633\u0645 \u0648 \u0627\u0644\u0623\u0645\u0627\u0643\u0646 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \/ SENSI WHITE KIT&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4964\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d9%86%d8%b3%d9%8a-%d9%88%d8%a7%d9%8a%d8%aa-%d8%ba%d8%b3%d9%88%d9%84-%d9%83%d8%b1%d9%8a%d9%85-%d9%84%d8%aa%d9%81%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%ac%d8%b3%d9%85-%d9%88-%d8%a7%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4964\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-4678 status-publish last instock product_cat-187 has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"4678\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/jamieson-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d8%a7%d9%84%d9%85%d8%ba%d9%86%d9%8a%d8%b3%d9%8a%d9%88%d9%85-100-%d9%85%d9%84%d8%ba-100%d9%82%d8%b1%d8%b5\/\" class=\"product-image-link\" aria-label=\"Jamieson \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0645\u063a\u0646\u064a\u0633\u064a\u0648\u0645 100 \u0645\u0644\u063a 100\u0642\u0631\u0635\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168.jpg 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-300x300.jpg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-150x150.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-600x600.jpg 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168.jpg 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-300x300.jpg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-150x150.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/05\/103168-600x600.jpg 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4678\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/jamieson-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d8%a7%d9%84%d9%85%d8%ba%d9%86%d9%8a%d8%b3%d9%8a%d9%88%d9%85-100-%d9%85%d9%84%d8%ba-100%d9%82%d8%b1%d8%b5\/\">Jamieson \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0645\u063a\u0646\u064a\u0633\u064a\u0648\u0645 100 \u0645\u0644\u063a 100\u0642\u0631\u0635<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/%d9%85%d9%83%d9%85%d9%84%d8%a7%d8%aa-%d8%ba%d8%b0%d8%a7%d8%a6%d9%8a%d8%a9\/\" rel=\"tag\">\u0645\u0643\u0645\u0644\u0627\u062a \u063a\u0630\u0627\u0626\u064a\u0629<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>55,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4678\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4678\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4678\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Jamieson \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0645\u063a\u0646\u064a\u0633\u064a\u0648\u0645 100 \u0645\u0644\u063a 100\u0642\u0631\u0635&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Jamieson \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0645\u063a\u0646\u064a\u0633\u064a\u0648\u0645 100 \u0645\u0644\u063a 100\u0642\u0631\u0635&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4678\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/jamieson-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d8%a7%d9%84%d9%85%d8%ba%d9%86%d9%8a%d8%b3%d9%8a%d9%88%d9%85-100-%d9%85%d9%84%d8%ba-100%d9%82%d8%b1%d8%b5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4678\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-3924 status-publish first instock product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"3924\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%85%d8%a8%d9%88%d9%84%d8%a7%d8%aa-%d9%86%d9%8a%d9%84%d9%84%d9%8a-nelly-ampoules\/\" class=\"product-image-link\" aria-label=\"\u0623\u0645\u0628\u0648\u0644\u0627\u062a \u0646\u064a\u0644\u0644\u064a NELLY AMPOULES\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10290.png\" class=\"attachment-large size-large\" alt=\"\u0623\u0645\u0628\u0648\u0644\u0627\u062a \u0646\u064a\u0644\u0644\u064a NELLY AMPOULES\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10290.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10290-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10290-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10290-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3924\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%85%d8%a8%d9%88%d9%84%d8%a7%d8%aa-%d9%86%d9%8a%d9%84%d9%84%d9%8a-nelly-ampoules\/\">\u0623\u0645\u0628\u0648\u0644\u0627\u062a \u0646\u064a\u0644\u0644\u064a NELLY AMPOULES<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>322,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3924\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3924\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3924\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;\u0623\u0645\u0628\u0648\u0644\u0627\u062a \u0646\u064a\u0644\u0644\u064a NELLY AMPOULES&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;\u0623\u0645\u0628\u0648\u0644\u0627\u062a \u0646\u064a\u0644\u0644\u064a NELLY AMPOULES&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3924\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%85%d8%a8%d9%88%d9%84%d8%a7%d8%aa-%d9%86%d9%8a%d9%84%d9%84%d9%8a-nelly-ampoules\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3924\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-3703 status-publish outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"5\" data-id=\"3703\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a5%d8%b3%d8%af%d9%8a%d9%86-%d8%a3%d9%83%d9%86%d9%8a%d8%a8%d9%8a%d9%86-%d9%83%d9%88%d9%86%d8%aa-%d8%ac%d8%b1%d8%a7%d9%86\/\" class=\"product-image-link\" aria-label=\"\u0625\u0633\u062f\u064a\u0646 \u0623\u0643\u0646\u064a\u0628\u064a\u0646 \u0643\u0648\u0646\u062a \u062c\u0631\u0627\u0646\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10233.png\" class=\"attachment-large size-large\" alt=\"\u0625\u0633\u062f\u064a\u0646 \u0623\u0643\u0646\u064a\u0628\u064a\u0646 \u0643\u0648\u0646\u062a \u062c\u0631\u0627\u0646\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10233.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10233-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10233-150x171.png 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3703\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a5%d8%b3%d8%af%d9%8a%d9%86-%d8%a3%d9%83%d9%86%d9%8a%d8%a8%d9%8a%d9%86-%d9%83%d9%88%d9%86%d8%aa-%d8%ac%d8%b1%d8%a7%d9%86\/\">\u0625\u0633\u062f\u064a\u0646 \u0623\u0643\u0646\u064a\u0628\u064a\u0646 \u0643\u0648\u0646\u062a \u062c\u0631\u0627\u0646<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>160,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a5%d8%b3%d8%af%d9%8a%d9%86-%d8%a3%d9%83%d9%86%d9%8a%d8%a8%d9%8a%d9%86-%d9%83%d9%88%d9%86%d8%aa-%d8%ac%d8%b1%d8%a7%d9%86\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3703\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"3703\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;\u0625\u0633\u062f\u064a\u0646 \u0623\u0643\u0646\u064a\u0628\u064a\u0646 \u0643\u0648\u0646\u062a \u062c\u0631\u0627\u0646&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3703\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a5%d8%b3%d8%af%d9%8a%d9%86-%d8%a3%d9%83%d9%86%d9%8a%d8%a8%d9%8a%d9%86-%d9%83%d9%88%d9%86%d8%aa-%d8%ac%d8%b1%d8%a7%d9%86\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3703\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-4012 status-publish outofstock product_cat-cosmetics-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4012\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%88%d8%a7%d9%82%d9%8a-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-%d8%a7%d9%84%d9%85%d9%87%d8%af%d8%a6-ngf37-cell\/\" class=\"product-image-link\" aria-label=\"\u0648\u0627\u0642\u064a \u0627\u0644\u0634\u0645\u0633 \u0627\u0644\u0645\u0647\u062f\u0626 NGF37 CELL\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10312.png\" class=\"attachment-large size-large\" alt=\"\u0648\u0627\u0642\u064a \u0627\u0644\u0634\u0645\u0633 \u0627\u0644\u0645\u0647\u062f\u0626 NGF37 CELL\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10312.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10312-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10312-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10312-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4012\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%88%d8%a7%d9%82%d9%8a-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-%d8%a7%d9%84%d9%85%d9%87%d8%af%d8%a6-ngf37-cell\/\">\u0648\u0627\u0642\u064a \u0627\u0644\u0634\u0645\u0633 \u0627\u0644\u0645\u0647\u062f\u0626 NGF37 CELL<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>218,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%88%d8%a7%d9%82%d9%8a-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-%d8%a7%d9%84%d9%85%d9%87%d8%af%d8%a6-ngf37-cell\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4012\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4012\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;\u0648\u0627\u0642\u064a \u0627\u0644\u0634\u0645\u0633 \u0627\u0644\u0645\u0647\u062f\u0626 NGF37 CELL&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4012\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%88%d8%a7%d9%82%d9%8a-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-%d8%a7%d9%84%d9%85%d9%87%d8%af%d8%a6-ngf37-cell\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4012\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-4150 status-publish last outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"7\" data-id=\"4150\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%88%d9%85%d9%8a%d9%83%d9%8a%d8%b1-30-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d9%82%d8%a7%d8%a8%d9%84%d8%a9-%d9%84%d9%84%d9%85%d8%b6%d8%ba-omecare\/\" class=\"product-image-link\" aria-label=\"\u0623\u0648\u0645\u064a\u0643\u064a\u0631 30 \u0623\u0642\u0631\u0627\u0635 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0645\u0636\u063a OMECARE\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10346.png\" class=\"attachment-large size-large\" alt=\"\u0623\u0648\u0645\u064a\u0643\u064a\u0631 30 \u0623\u0642\u0631\u0627\u0635 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0645\u0636\u063a OMECARE\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10346.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10346-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10346-150x171.png 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4150\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%88%d9%85%d9%8a%d9%83%d9%8a%d8%b1-30-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d9%82%d8%a7%d8%a8%d9%84%d8%a9-%d9%84%d9%84%d9%85%d8%b6%d8%ba-omecare\/\">\u0623\u0648\u0645\u064a\u0643\u064a\u0631 30 \u0623\u0642\u0631\u0627\u0635 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0645\u0636\u063a OMECARE<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>149,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%88%d9%85%d9%8a%d9%83%d9%8a%d8%b1-30-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d9%82%d8%a7%d8%a8%d9%84%d8%a9-%d9%84%d9%84%d9%85%d8%b6%d8%ba-omecare\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4150\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4150\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;\u0623\u0648\u0645\u064a\u0643\u064a\u0631 30 \u0623\u0642\u0631\u0627\u0635 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0645\u0636\u063a OMECARE&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4150\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a3%d9%88%d9%85%d9%8a%d9%83%d9%8a%d8%b1-30-%d8%a3%d9%82%d8%b1%d8%a7%d8%b5-%d9%82%d8%a7%d8%a8%d9%84%d8%a9-%d9%84%d9%84%d9%85%d8%b6%d8%ba-omecare\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4150\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-buttons-on-hover wd-col product-grid-item product type-product post-3381 status-publish first instock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"8\" data-id=\"3381\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%85%d8%b3%d8%ad%d9%88%d9%82-%d9%81%d9%8a%d9%84%d9%88%d9%86%d8%a7-20-%d9%83%d9%8a%d8%b3\/\" class=\"product-image-link\" aria-label=\"\u0645\u0633\u062d\u0648\u0642 \u0641\u064a\u0644\u0648\u0646\u0627 20 \u0643\u064a\u0633\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10156.png\" class=\"attachment-large size-large\" alt=\"\u0645\u0633\u062d\u0648\u0642 \u0641\u064a\u0644\u0648\u0646\u0627 20 \u0643\u064a\u0633\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10156.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10156-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10156-150x171.png 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3381\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%85%d8%b3%d8%ad%d9%88%d9%82-%d9%81%d9%8a%d9%84%d9%88%d9%86%d8%a7-20-%d9%83%d9%8a%d8%b3\/\">\u0645\u0633\u062d\u0648\u0642 \u0641\u064a\u0644\u0648\u0646\u0627 20 \u0643\u064a\u0633<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>129,56&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3381\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3381\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3381\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;\u0645\u0633\u062d\u0648\u0642 \u0641\u064a\u0644\u0648\u0646\u0627 20 \u0643\u064a\u0633&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;\u0645\u0633\u062d\u0648\u0642 \u0641\u064a\u0644\u0648\u0646\u0627 20 \u0643\u064a\u0633&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3381\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%85%d8%b3%d8%ad%d9%88%d9%82-%d9%81%d9%8a%d9%84%d9%88%d9%86%d8%a7-20-%d9%83%d9%8a%d8%b3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3381\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-3da56a9 e-flex e-con-boxed e-con e-parent\" data-id=\"3da56a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-db98ead e-flex e-con-boxed e-con e-child\" data-id=\"db98ead\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6cbb3 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"7e6cbb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Hair Care Products<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d9c4ff elementor-widget elementor-widget-wd_button\" data-id=\"5d9c4ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-large btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/dr-glo.store\/en\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVisit Shop\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-f7e100b e-flex e-con-boxed e-con e-parent\" data-id=\"f7e100b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-0689462 e-flex e-con-boxed e-con e-child\" data-id=\"0689462\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8cb5e5 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"d8cb5e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Sale<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb92d2 elementor-widget elementor-widget-wd_button\" data-id=\"4cb92d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-large btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/dr-glo.store\/en\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVisit Shop\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b0221 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"21b0221\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-936\" class=\"wd-carousel-container  wd-products-element wd-products products wd-products-with-bg wd-products-with-shadow wd-stretch-cont-lg products-bordered-grid-ins title-line-one\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid wd-stretch-cont-lg\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5.5;--wd-col-md:3.5;--wd-col-sm:1.5;--wd-gap:20px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-1897 status-publish instock product_cat-skin-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1897\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\" class=\"product-image-link\" aria-label=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png\" class=\"attachment-medium_large size-medium_large\" alt=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"1897\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"1897\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=1897\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1897\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"1897\" data-product_sku=\"3700111428478\" aria-label=\"Add to cart: &ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1897\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\">-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>109,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-4244 status-publish outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"4244\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" class=\"product-image-link\" aria-label=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png\" class=\"attachment-medium_large size-medium_large\" alt=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4244\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4244\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4244\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4244\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Read more<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4244\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\">% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>235,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product wcpa_has_options type-product post-2868 status-publish last instock product_cat-medicine-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"2868\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"AV AVOHEX M W 300 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"800\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png\" class=\"attachment-medium_large size-medium_large\" alt=\"AV AVOHEX M W 300 \u0645\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png 700w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-65x74.png 65w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"2868\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"2868\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2868\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button wcpa_add_to_cart_button add-to-cart-loop\" data-product_id=\"2868\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AV AVOHEX M W 300 \u0645\u0644&rdquo; has been added to your cart\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2868\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\">AV AVOHEX M W 300 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/medicine-2\/\" rel=\"tag\">\u0627\u0644\u0627\u062f\u0648\u064a\u0629 \u0627\u0644\u0648\u0635\u0641\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>37,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4840 status-publish first instock product_cat-hair-2 product_cat-scalp-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"4840\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4840\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4840\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4840\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4840\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4840\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4840\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/hair-2\/\" rel=\"tag\">\u0627\u0644\u0634\u0639\u0631<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/scalp-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0641\u0631\u0648\u0629 \u0627\u0644\u0631\u0623\u0633<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>132,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4867 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-serums-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"4867\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-768x786.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1501x1536.jpeg 1501w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-1200x1228.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e.jpeg 1564w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4867\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4867\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4867\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4867\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4867\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4867\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>350,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4876 status-publish instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4876\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-768x785.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1502x1536.jpeg 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-1200x1227.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01.jpeg 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4876\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4876\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4876\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4876\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4876\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4876\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>310,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3028 status-publish last instock product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"3028\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"786\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-768x786.jpg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-293x300.jpg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1001x1024.jpg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-1200x1228.jpg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-150x153.jpg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f.jpg 1251w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3028\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3028\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3028\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3028\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3028\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3028\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>115,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4845 status-publish first instock product_cat-skin-care-2 product_cat-serums-2 product_cat-body-lotions-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"4845\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-768x785.png 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-293x300.png 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1001x1024.png 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1502x1536.png 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-1200x1227.png 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-150x153.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d.png 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4845\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4845\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4845\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4845\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4845\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4845\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/serums-2\/\" rel=\"tag\">\u0633\u064a\u0631\u0648\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4871 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-cleansers-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"4871\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-768x785.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-768x785.png 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-293x300.png 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1001x1024.png 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1502x1536.png 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-1200x1227.png 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-150x153.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1.png 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4871\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4871\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4871\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4871\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4871\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4871\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cleansers-2\/\" rel=\"tag\">\u063a\u0633\u0648\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>184,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3040 status-publish instock product_cat-skin-care-2 product_cat-creams-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"3040\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"785\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-768x785.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-768x785.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-293x300.jpeg 293w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1001x1024.jpeg 1001w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1502x1536.jpeg 1502w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-1200x1227.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-150x153.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51.jpeg 1956w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3040\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3040\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3040\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3040\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3040\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3040\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\">Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/creams-2\/\" rel=\"tag\">\u0643\u0631\u064a\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-4836 status-publish last instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"4836\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-768x768.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-300x300.jpeg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-150x150.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-600x600.jpeg 600w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233.jpeg 770w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4836\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"4836\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=4836\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4836\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4836\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4836\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\">Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/skin-care-2\/\" rel=\"tag\">\u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/face-sunscreen-2\/\" rel=\"tag\">\u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0644\u0644\u0648\u062c\u0647<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>172,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-3020 status-publish first instock product_cat-158 product_cat-conditioners-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"3020\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-768x768.jpeg 768w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-300x300.jpeg 300w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1024x1024.jpeg 1024w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-150x150.jpeg 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1536x1536.jpeg 1536w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-600x600.jpeg 600w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-1200x1200.jpeg 1200w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4.jpeg 1600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"3020\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/dr-glo.store\/en\/wishlist\/\" data-key=\"f0a9aeea04\" data-product-id=\"3020\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1070?add-to-cart=3020\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3020\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3020\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Care&amp;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Care&amp;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a&rdquo; has been added to your cart\" role=\"button\"><span>Add to cart<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3020\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"product-element-bottom\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\">Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics\/skin-care\/%d8%a7%d9%84%d8%b4%d9%81%d8%a7%d9%87\/\" rel=\"tag\">\u0627\u0644\u0634\u0641\u0627\u0647<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/conditioners-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/body-lotions-2\/\" rel=\"tag\">\u0645\u0631\u0637\u0628\u0627\u062a \u0627\u0644\u062c\u0633\u0645<\/a>, <a href=\"https:\/\/dr-glo.store\/en\/product-category\/cosmetics-2\/\" rel=\"tag\">\u0645\u0633\u062a\u062d\u0636\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0645\u064a\u0644<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-scroll\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-9f5a710 e-flex e-con-boxed e-con e-parent\" data-id=\"9f5a710\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d35ff87 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"d35ff87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-553\" class=\"wd-carousel-container  with-title wd-products-element wd-products products wd-products-with-bg wd-products-with-shadow products-bordered-grid-ins title-line-one\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"wd-el-title title slider-title element-title\"><span>Last Visited Products<\/span><\/h4>\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5;--wd-col-md:3;--wd-col-sm:1;--wd-gap:20px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-1897 status-publish instock product_cat-skin-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1897\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\" class=\"product-image-link\" aria-label=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png\" class=\"attachment-65x74 size-65x74\" alt=\"-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-65x74.png 65w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/01\/168.png 700w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d9%85%d9%8a%d9%86%d9%83-8-%d8%ac%d9%84-%d9%86%d9%8a%d8%b1%d8%aa%d8%a7%d9%84%d9%8a%d8%b2-%d8%a8%d8%a7%d9%8a%d9%88-%d8%a3%d9%84%d8%aa%d8%b1%d8%a7-%d8%ac%d9%8a%d9%86%d8%aa%d9%84\/\">-\u0641\u064a\u0645\u064a\u0646\u0643-8 -\u062c\u0644 \u0646\u064a\u0631\u062a\u0627\u0644\u064a\u0632 \u0628\u0627\u064a\u0648 \u0623\u0644\u062a\u0631\u0627-\u062c\u064a\u0646\u062a\u0644<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>109,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-small product-grid-item product type-product post-4244 status-publish outofstock product_cat-cosmetics-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"4244\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\" class=\"product-image-link\" aria-label=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-65x74.png\" class=\"attachment-65x74 size-65x74\" alt=\"% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-65x74.png 65w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/10369.png 700w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%86-%d9%83%d8%a7%d8%a8%d9%8a%d9%86%d9%88%d9%86-%d9%83-1-pharmaceris\/\">% \u0646 \u0643\u0627\u0628\u064a\u0646\u0648\u0646 \u0643 1 PHARMACERIS<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>235,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product wcpa_has_options type-product post-2868 status-publish last instock product_cat-medicine-2 has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"2868\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"AV AVOHEX M W 300 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-65x74.png\" class=\"attachment-65x74 size-65x74\" alt=\"AV AVOHEX M W 300 \u0645\u0644\" srcset=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-65x74.png 65w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-263x300.png 263w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133-150x171.png 150w, https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/03\/133.png 700w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/av-avohex-m-w-300-%d9%85%d9%84\/\">AV AVOHEX M W 300 \u0645\u0644<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>37,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4840 status-publish first instock product_cat-hair-2 product_cat-scalp-care-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"4840\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/10227110-bc03-4d06-8645-48a85e312905-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b2%d9%8a%d8%aa-%d8%a7%d9%84%d8%a3%d8%b1%d8%ac%d8%a7%d9%86-%d9%84%d9%84%d8%b4%d8%b9%d8%b1-100-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0632\u064a\u062a \u0627\u0644\u0623\u0631\u062c\u0627\u0646 \u0644\u0644\u0634\u0639\u0631 100 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>132,25&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4867 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-serums-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"4867\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/522d463f-334a-4cd6-b124-bb1c3f71161e-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d8%ad%d9%85%d8%b6-%d8%a7%d9%84%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d9%85%d8%b9-%d8%ac%d9%84%d9%88%d8%aa%d8%a7%d8%ab%d9%8a%d9%88%d9%86-50-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u062d\u0645\u0636 \u0627\u0644\u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0645\u0639 \u062c\u0644\u0648\u062a\u0627\u062b\u064a\u0648\u0646 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>350,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4876 status-publish instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4876\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/a848943f-41ad-4455-a5b9-5a3fdb0e8f01-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%81%d9%8a%d8%aa%d8%a7%d9%85%d9%8a%d9%86-%d8%b3%d9%8a-%d9%85%d8%b9-%d9%87%d9%8a%d8%a7%d9%84%d9%88%d8%b1%d9%86%d9%8a%d9%83-%d8%a3%d8%b3%d8%af-50-%d9%85%d9%84-%d9%85\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0641\u064a\u062a\u0627\u0645\u064a\u0646 \u0633\u064a \u0645\u0639 \u0647\u064a\u0627\u0644\u0648\u0631\u0646\u064a\u0643 \u0623\u0633\u062f 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>310,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-3028 status-publish last instock product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"3028\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-08-07-at-15.10.09_5f1a879f-65x74.jpg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%a8%d8%b1%d8%a7%d9%8a%d9%85%d8%b1-%d8%b3%d9%8a-%d8%a8%d9%8a-30-%d9%85%d9%84\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0642\u0628\u0644 \u0648\u0636\u0639 \u0627\u0644\u0645\u0643\u064a\u0627\u062c \u0628\u0631\u0627\u064a\u0645\u0631 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a 30 \u0645\u0644<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>115,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4845 status-publish first instock product_cat-skin-care-2 product_cat-serums-2 product_cat-body-lotions-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"4845\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/d9b7a6db-c5f3-4f94-b72e-704bd538428d-65x74.png\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a%d8%b1%d9%88%d9%85-%d9%86%d8%b6%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-50-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u0633\u064a\u0631\u0648\u0645 \u0646\u0636\u0627\u0631\u0629 \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4871 status-publish instock product_cat-skin-care-2 product_cat-body-2 product_cat-cleansers-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"4871\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/5fc06567-a801-4d24-bc0e-4e55e3102ea1-65x74.png\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%ba%d8%b3%d9%88%d9%84-%d9%85%d9%81%d8%aa%d8%ad-%d9%84%d9%84%d9%88%d8%ac%d9%87-200-%d9%85%d9%84-%d9%85%d9%86-%d9%83%d9%8a%d8%b1-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a\/\">Care&#038;Beauty\/\u063a\u0633\u0648\u0644 \u0645\u0641\u062a\u062d \u0644\u0644\u0648\u062c\u0647 200 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>184,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-3040 status-publish instock product_cat-skin-care-2 product_cat-creams-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"3040\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/dec702ef-10ab-4ba6-a352-0e47cfa7fa51-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%aa%d8%a8%d9%8a%d9%8a%d8%b6-%d8%b3%d9%8a-%d8%a8%d9%8a\/\">Care&#038;Beauty\/\u0643\u0631\u064a\u0645 \u062a\u0641\u062a\u064a\u062d \u0627\u0644\u0628\u0634\u0631\u0629 50 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>327,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-4836 status-publish last instock product_cat-skin-care-2 product_cat-sunscreen-2 product_cat-body-sunscreen-2 product_cat-face-sunscreen-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"4836\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/08\/96683233-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d9%8a%d8%b1-%d8%a7%d9%86%d8%af-%d8%a8%d9%8a%d9%88%d8%aa%d9%8a-%d8%b3%d8%a7%d8%a6%d9%84-%d9%88%d8%a7%d9%82%d9%8a-%d8%b4%d9%85%d8%b3-%d9%85%d8%b9%d8%a7%d9%85%d9%84-%d8%ad%d9%85%d8%a7%d9%8a%d8%a9\/\">Care&#038;Beauty\/\u0643\u064a\u0631 \u0627\u0646\u062f \u0628\u064a\u0648\u062a\u064a \u0633\u0627\u0626\u0644 \u0648\u0627\u0642\u064a \u0634\u0645\u0633 \u0645\u0639\u0627\u0645\u0644 \u062d\u0645\u0627\u064a\u0629+50 50\u0645\u0644<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>172,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-small product-grid-item product type-product post-3020 status-publish first instock product_cat-158 product_cat-conditioners-2 product_cat-body-lotions-2 product_cat-cosmetics-2 has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"3020\">\n\t\n\t\n\n\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top\">\n\t\t<a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\" class=\"product-image-link\" aria-label=\"Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/dr-glo.store\/wp-content\/uploads\/2025\/04\/1b6b0561-6235-4ba8-82a8-2951e6476bf4-65x74.jpeg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/dr-glo.store\/en\/shop\/%d8%b3%d9%8a-%d8%a8%d9%8a-%d9%85%d8%a7%d8%ac%d9%8a%d9%83-%d9%84%d9%8a%d8%a8\/\">Care&#038;Beauty\/\u0645\u0631\u0637\u0628 \u0627\u0644\u0634\u0641\u0627\u064a\u0641 \u0627\u0644\u0633\u062d\u0631\u064a 10 \u0645\u0644 \u0645\u0646 \u0643\u064a\u0631 \u0628\u064a\u0648\u062a\u064a<\/a><\/h3>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x633;<\/span><\/bdi><\/span><\/span>\n\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-scroll\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Shop By Brand Weekly Offers Visit Shop -4% Quick view Add to wishlist Add to cart VITRO SCAR &#8211; \u0641\u064a\u062a\u0631\u0648<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1070","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/pages\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/comments?post=1070"}],"version-history":[{"count":130,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/pages\/1070\/revisions"}],"predecessor-version":[{"id":4658,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/pages\/1070\/revisions\/4658"}],"wp:attachment":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media?parent=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}