{"id":3405,"date":"2025-04-21T10:06:59","date_gmt":"2025-04-21T10:06:59","guid":{"rendered":"https:\/\/dr-glo.store\/?post_type=product&#038;p=3405"},"modified":"2026-03-31T14:04:33","modified_gmt":"2026-03-31T14:04:33","slug":"%d9%81%d9%8a%d8%b1%d8%aa%d8%a7%d9%85%d9%88%d9%84-30-%d9%83%d9%8a%d8%b3","status":"publish","type":"product","link":"https:\/\/dr-glo.store\/en\/shop\/%d9%81%d9%8a%d8%b1%d8%aa%d8%a7%d9%85%d9%88%d9%84-30-%d9%83%d9%8a%d8%b3\/","title":{"rendered":"\u0641\u064a\u0631\u062a\u0627\u0645\u0648\u0644 30 \u0643\u064a\u0633"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3406,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[166],"product_tag":[],"class_list":{"0":"post-3405","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cosmetics-2","8":"first","9":"outofstock","10":"purchasable","11":"product-type-simple"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/comments?post=3405"}],"version-history":[{"count":1,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3405\/revisions"}],"predecessor-version":[{"id":3408,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3405\/revisions\/3408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media\/3406"}],"wp:attachment":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media?parent=3405"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_brand?post=3405"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_cat?post=3405"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_tag?post=3405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}