{"id":3577,"date":"2025-04-21T19:36:05","date_gmt":"2025-04-21T19:36:05","guid":{"rendered":"https:\/\/dr-glo.store\/?post_type=product&#038;p=3577"},"modified":"2025-04-21T19:36:06","modified_gmt":"2025-04-21T19:36:06","slug":"%d8%ad%d9%84%d9%8a%d8%a8-%d9%85%d8%b1%d8%b7%d8%a8-%d9%87%d9%8a%d9%84%d9%8a%d8%a7%d8%a8%d8%b1%d9%8a%d9%86","status":"publish","type":"product","link":"https:\/\/dr-glo.store\/en\/shop\/%d8%ad%d9%84%d9%8a%d8%a8-%d9%85%d8%b1%d8%b7%d8%a8-%d9%87%d9%8a%d9%84%d9%8a%d8%a7%d8%a8%d8%b1%d9%8a%d9%86\/","title":{"rendered":"\u062d\u0644\u064a\u0628 \u0645\u0631\u0637\u0628 \u0647\u064a\u0644\u064a\u0627\u0628\u0631\u064a\u0646"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3578,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[166],"product_tag":[],"class_list":{"0":"post-3577","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cosmetics-2","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":1,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3577\/revisions"}],"predecessor-version":[{"id":3580,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3577\/revisions\/3580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media\/3578"}],"wp:attachment":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_brand?post=3577"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_cat?post=3577"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_tag?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}