{"id":3839,"date":"2025-04-27T18:13:20","date_gmt":"2025-04-27T18:13:20","guid":{"rendered":"https:\/\/dr-glo.store\/?post_type=product&#038;p=3839"},"modified":"2025-04-27T18:13:21","modified_gmt":"2025-04-27T18:13:21","slug":"%d8%ac%d9%84-%d9%85%d8%a7%d8%af-%d9%81%d9%8a%d8%af-4","status":"publish","type":"product","link":"https:\/\/dr-glo.store\/en\/shop\/%d8%ac%d9%84-%d9%85%d8%a7%d8%af-%d9%81%d9%8a%d8%af-4\/","title":{"rendered":"\u062c\u0644 \u0645\u0627\u062f \u0641\u064a\u062f 4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3840,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[166],"product_tag":[],"class_list":{"0":"post-3839","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cosmetics-2","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/comments?post=3839"}],"version-history":[{"count":1,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3839\/revisions"}],"predecessor-version":[{"id":3842,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/3839\/revisions\/3842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media\/3840"}],"wp:attachment":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media?parent=3839"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_brand?post=3839"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_cat?post=3839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_tag?post=3839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}