{"id":4280,"date":"2025-04-29T20:22:54","date_gmt":"2025-04-29T20:22:54","guid":{"rendered":"https:\/\/dr-glo.store\/?post_type=product&#038;p=4280"},"modified":"2025-04-29T20:22:54","modified_gmt":"2025-04-29T20:22:54","slug":"%d9%83%d8%b1%d9%8a%d9%85-%d8%a8%d8%b1%d9%88%d9%83%d8%aa%d9%88-procto-cream","status":"publish","type":"product","link":"https:\/\/dr-glo.store\/en\/shop\/%d9%83%d8%b1%d9%8a%d9%85-%d8%a8%d8%b1%d9%88%d9%83%d8%aa%d9%88-procto-cream\/","title":{"rendered":"\u0643\u0631\u064a\u0645 \u0628\u0631\u0648\u0643\u062a\u0648 PROCTO CREAM"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4281,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[175],"product_tag":[],"class_list":{"0":"post-4280","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-creams-2","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/4280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/comments?post=4280"}],"version-history":[{"count":1,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/4280\/revisions"}],"predecessor-version":[{"id":4283,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product\/4280\/revisions\/4283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media\/4281"}],"wp:attachment":[{"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/media?parent=4280"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_brand?post=4280"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_cat?post=4280"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dr-glo.store\/en\/wp-json\/wp\/v2\/product_tag?post=4280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}